{"id":7026,"date":"2024-06-10T13:56:28","date_gmt":"2024-06-10T11:56:28","guid":{"rendered":"https:\/\/reverent-antonelli.23-88-7-78.plesk.page\/media-reports\/"},"modified":"2025-04-28T14:38:30","modified_gmt":"2025-04-28T12:38:30","slug":"media-reports","status":"publish","type":"page","link":"https:\/\/normativeorders.net\/en\/media-reports\/","title":{"rendered":"Media reports"},"content":{"rendered":"                    <section class=\"press-review\" data-category=\"[]\" data-numberposts=\"12\">\n            <div class=\"container\">\n                <h1>Media reports<\/h1>\n                \n<div class=\"block-press-review row\">\n\n    \n                        <div class=\"col-lg-6\">\n                                            <div class=\"box-item\">\n                            <div class=\"box-date\">5. July 2026| Artikel<\/div>\n                            <h3><a href=\"https:\/\/www.tagesschau.de\/inland\/regional\/badenwuerttemberg\/swr-nach-pfeffersprayeinsatz-in-singen-ist-die-polizei-gut-vorbereitet-100.html\">Nach\u00a0Pfeffersprayeinsatz\u00a0in Singen: Ist die Polizei gut vorbereitet?<\/a><\/h3>\n                                                            <p>Polizisten sind in Eins\u00e4tzen immer wieder mit Menschen in psychischen Ausnahmesituationen konfrontiert. Wie gut ist die Polizei auf solche Situationen vorbereitet? Mit Einsch\u00e4tzungen von Tobias Singelnstein. (tagesschau)<\/p>\n                                                        <a class=\"box-link\" href=\"https:\/\/www.tagesschau.de\/inland\/regional\/badenwuerttemberg\/swr-nach-pfeffersprayeinsatz-in-singen-ist-die-polizei-gut-vorbereitet-100.html\">zum Beitrag \u203a<\/a>\n                        <\/div>\n                                            <div class=\"box-item\">\n                            <div class=\"box-date\">22. June 2026| Bericht, Habermas-Gedenken<\/div>\n                            <h3><a href=\"https:\/\/www.fr.de\/kultur\/gesellschaft\/habermas-symposium-philosoph-forst-warnt-vor-musealer-verehrung-94362891.html\">Symposium an der Goethe-Uni: Ohne Habermas mit Habermas denken<\/a><\/h3>\n                                                            <p>Ein Symposium auf dem Westend-Campus vermisst das Werk des im M\u00e4rz verstorbenen J\u00fcrgen Habermas. Sein Sch\u00fcler Rainer Forst forderte, den \u201eMaulwurf der Vernunft&#8221; weiterarbeiten zu lassen. Ein Bericht des internationalen Symposiums zu Ehren von J\u00fcrgen Habermas. (Frankfurter Rundschau)<\/p>\n                                                        <a class=\"box-link\" href=\"https:\/\/www.fr.de\/kultur\/gesellschaft\/habermas-symposium-philosoph-forst-warnt-vor-musealer-verehrung-94362891.html\">zum Beitrag \u203a<\/a>\n                        <\/div>\n                                            <div class=\"box-item\">\n                            <div class=\"box-date\">22. June 2026| Bericht, Habermas-Gedenken<\/div>\n                            <h3><a href=\"https:\/\/www.sueddeutsche.de\/kultur\/habermas-trauerfeier-frankfurter-paulskirche-steinmeier-philosoph-li.3496289\">Und jetzt weitermachen in seinem Sinn<\/a><\/h3>\n                                                            <p>In der Frankfurter Paulskirche nehmen Wegbegleiter, Intellektuelle und Politiker Abschied von J\u00fcrgen Habermas. Keine Soldaten, keine Geistlichen, daf\u00fcr viele gute Reden. Ein Bericht \u00fcber die Gedenkstunde f\u00fcr J\u00fcrgen Habermas. (S\u00fcddeutsche Zeitung)<\/p>\n                                                        <a class=\"box-link\" href=\"https:\/\/www.sueddeutsche.de\/kultur\/habermas-trauerfeier-frankfurter-paulskirche-steinmeier-philosoph-li.3496289\">zum Beitrag \u203a<\/a>\n                        <\/div>\n                                            <div class=\"box-item\">\n                            <div class=\"box-date\">19. June 2026| Bericht, Habermas-Gedenken<\/div>\n                            <h3><a href=\"https:\/\/www.spiegel.de\/kultur\/juergen-habermas-wem-gehoert-der-beruehmte-philosoph-a-c00e2b39-9bf3-4957-ba14-1fd9680043c8\">Gedenken an den Philosophen: Wem geh\u00f6rt J\u00fcrgen Habermas?<\/a><\/h3>\n                                                            <p>Ist es deprimierend, wenn der Bundespr\u00e4sident die beste Rede h\u00e4lt? Politiker und Intellektuelle gedachten in Frankfurt des Philosophen J\u00fcrgen Habermas \u2013 warum waren sie dabei so ratlos? Ein Bericht der Gedenkstunde f\u00fcr J\u00fcrgen Habermas. (Spiegel)<\/p>\n                                                        <a class=\"box-link\" href=\"https:\/\/www.spiegel.de\/kultur\/juergen-habermas-wem-gehoert-der-beruehmte-philosoph-a-c00e2b39-9bf3-4957-ba14-1fd9680043c8\">zum Beitrag \u203a<\/a>\n                        <\/div>\n                                            <div class=\"box-item\">\n                            <div class=\"box-date\">19. June 2026| Bericht, Habermas-Gedenken<\/div>\n                            <h3><a href=\"https:\/\/www.hessenschau.de\/gesellschaft\/gedenkstunde-fuer-juergen-habermas-seine-stimme-wird-uns-fehlen-in-diesen-unuebersichtlichen-zeiten-v1,gedenkstunde-juergen-habermas-paulskirche-100.html\">&#8220;Seine Stimme wird uns fehlen in diesen un\u00fcbersichtlichen Zeiten&#8221;<\/a><\/h3>\n                                                            <p>Drei Monate nach seinem Tod haben Weggef\u00e4hrten, Politiker und Wissenschaftler in der Frankfurter Paulskirche an den Philosophen J\u00fcrgen Habermas erinnert. Im Mittelpunkt standen sein Einsatz f\u00fcr Demokratie und die Sorge um den Zustand des \u00f6ffentlichen Diskurses. Ein Bericht \u00fcber die gednekstunde f\u00fcr J\u00fcrgen Habermas. (hessenschau)<\/p>\n                                                        <a class=\"box-link\" href=\"https:\/\/www.hessenschau.de\/gesellschaft\/gedenkstunde-fuer-juergen-habermas-seine-stimme-wird-uns-fehlen-in-diesen-unuebersichtlichen-zeiten-v1,gedenkstunde-juergen-habermas-paulskirche-100.html\">zum Beitrag \u203a<\/a>\n                        <\/div>\n                                            <div class=\"box-item\">\n                            <div class=\"box-date\">19. June 2026| Bericht, Habermas-Gedenken<\/div>\n                            <h3><a href=\"https:\/\/www.welt.de\/kultur\/article6a33d3c546cd409e901a5b60\/gedenkstunde-fuer-philosophen-unsere-demokratie-und-unser-habermas.html\">Gedenkstunde f\u00fcr Philosophen: Unsere Demokratie und unser Habermas<\/a><\/h3>\n                                                            <p>Marc Reichwein \u00fcber die Gedenkstunde f\u00fcr J\u00fcrgen Habermas in der Paulskirche (WELT).<\/p>\n                                                        <a class=\"box-link\" href=\"https:\/\/www.welt.de\/kultur\/article6a33d3c546cd409e901a5b60\/gedenkstunde-fuer-philosophen-unsere-demokratie-und-unser-habermas.html\">zum Beitrag \u203a<\/a>\n                        <\/div>\n                                    <\/div>\n                                    <div class=\"col-lg-6\">\n                                            <div class=\"box-item\">\n                            <div class=\"box-date\">24. June 2026| Bericht, Habermas-Gedenken<\/div>\n                            <h3><a href=\"https:\/\/www.faz.net\/aktuell\/wissen\/geist-soziales\/hat-juergen-habermas-schule-gemacht-200955774.html\">Habermas-Symposium: Ist er wirklich unnachahmlich?<\/a><\/h3>\n                                                            <p>Wie J\u00fcrgen Habermas seinen Lehrer Adorno auch nach dessen Tod ins Gespr\u00e4ch zog und brachte, zeigte auf dem Frankfurter Gedenksymposium Axel Honneth. Wer von den Sch\u00fclern redet nun weiter mit und wie Habermas? (Frankfurter Allgemeine Zeitung)<\/p>\n                                                        <a class=\"box-link\" href=\"https:\/\/www.faz.net\/aktuell\/wissen\/geist-soziales\/hat-juergen-habermas-schule-gemacht-200955774.html\">zum Beitrag \u203a<\/a>\n                        <\/div>\n                                            <div class=\"box-item\">\n                            <div class=\"box-date\">22. June 2026| Bericht, Habermas-Gedenken<\/div>\n                            <h3><a href=\"https:\/\/www.faz.net\/aktuell\/feuilleton\/debatten\/frank-walter-steinmeier-wuerdigt-juergen-habermas-in-der-paulskirche-200945447.html\">Die Welt um ein Winziges besser machen<\/a><\/h3>\n                                                            <p>Ungebrochene Energie des Dagegenhaltens: In der Frankfurter Paulskirche w\u00fcrdigte der Bundespr\u00e4sident den am 14. M\u00e4rz verstorbenen Philosophen J\u00fcrgen Habermas. Ein Bericht. (Frankfurter Allgemeine Zeitung)<\/p>\n                                                        <a class=\"box-link\" href=\"https:\/\/www.faz.net\/aktuell\/feuilleton\/debatten\/frank-walter-steinmeier-wuerdigt-juergen-habermas-in-der-paulskirche-200945447.html\">zum Beitrag \u203a<\/a>\n                        <\/div>\n                                            <div class=\"box-item\">\n                            <div class=\"box-date\">20. June 2026| Bericht, Habermas-Gedenken<\/div>\n                            <h3><a href=\"https:\/\/www.zeit.de\/feuilleton\/2026-06\/juergen-habermas-paulskirche-frankfurt-gedenkfeier-steinmeier\/komplettansicht\">J\u00fcrgen Habermas: Umk\u00e4mpftes Erbe<\/a><\/h3>\n                                                            <p>Philosophen, Verleger und ein Bundespr\u00e4sident: In der Frankfurter Paulskirche wurde an den verstorbenen Philosophen J\u00fcrgen Habermas erinnert. Wie aktuell ist sein Denken? \u00dcber die Gedenkstunde f\u00fcr J\u00fcrgen Habermas in der Frankfurter Paulskirche. (Die Zeit)<\/p>\n                                                        <a class=\"box-link\" href=\"https:\/\/www.zeit.de\/feuilleton\/2026-06\/juergen-habermas-paulskirche-frankfurt-gedenkfeier-steinmeier\/komplettansicht\">zum Beitrag \u203a<\/a>\n                        <\/div>\n                                            <div class=\"box-item\">\n                            <div class=\"box-date\">19. June 2026| Bericht, Habermas-Gedenken<\/div>\n                            <h3><a href=\"https:\/\/taz.de\/Gedenkstunde-fuer-Juergen-Habermas\/!6189000\/\">Gegen die Mechanismen der Macht<\/a><\/h3>\n                                                            <p>Bundespr\u00e4sident Steinmeier w\u00fcrdigte den Philosophen J\u00fcrgen Habermas in der Frankfurter Paulskirche. Zum Gl\u00fcck hatte die Gedenkstunde wenig Weihevolles. Ein Bericht \u00fcber die Gedenkstunde f\u00fcr J\u00fcrgen Habermas. (taz)<\/p>\n                                                        <a class=\"box-link\" href=\"https:\/\/taz.de\/Gedenkstunde-fuer-Juergen-Habermas\/!6189000\/\">zum Beitrag \u203a<\/a>\n                        <\/div>\n                                            <div class=\"box-item\">\n                            <div class=\"box-date\">19. June 2026| Bericht, Habermas-Gedenken<\/div>\n                            <h3><a href=\"https:\/\/www.fr.de\/kultur\/gesellschaft\/steinmeier-wuerdigt-juergen-habermas-in-der-paulskirche-94359729.html\">Gedenkveranstaltung in der Paulskirche: \u201eIch dachte laut mit Habermas\u201c<\/a><\/h3>\n                                                            <p>Bericht \u00fcber die Gedenkveranstaltung f\u00fcr J\u00fcrgen Habermas in der Paulskirche. (Frankfurter Rundschau)<\/p>\n                                                        <a class=\"box-link\" href=\"https:\/\/www.fr.de\/kultur\/gesellschaft\/steinmeier-wuerdigt-juergen-habermas-in-der-paulskirche-94359729.html\">zum Beitrag \u203a<\/a>\n                        <\/div>\n                                            <div class=\"box-item\">\n                            <div class=\"box-date\">19. June 2026| Gastbeitrag, Habermas-Gedenken<\/div>\n                            <h3><a href=\"https:\/\/www.sueddeutsche.de\/kultur\/norbert-frei-juergen-habermas-gedenkstunde-li.3493178\">Philosophie\u201eEs musste etwas besser werden \u2026\u201c<\/a><\/h3>\n                                                            <p>Wie hat J\u00fcrgen Habermas die Bundesrepublik und ihre Debatten gepr\u00e4gt? Die Rede des Historikers Norbert Frei bei der Gedenkstunde f\u00fcr den im M\u00e4rz verstorbenen Philosophen in der Frankfurter Paulskirche. (S\u00fcddeutsche Zeitung)<\/p>\n                                                        <a class=\"box-link\" href=\"https:\/\/www.sueddeutsche.de\/kultur\/norbert-frei-juergen-habermas-gedenkstunde-li.3493178\">zum Beitrag \u203a<\/a>\n                        <\/div>\n                                    <\/div>\n                    \n    <\/div>\n\n<div class=\"pagination js-paged-medienecho\"><span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"?paged=2\">2<\/a>\n<a class=\"page-numbers\" href=\"?paged=3\">3<\/a>\n<a class=\"page-numbers\" href=\"?paged=4\">4<\/a>\n<span class=\"page-numbers dots\">&hellip;<\/span>\n<a class=\"page-numbers\" href=\"?paged=13\">13<\/a><\/div>\n            <\/div>\n        <\/section>\n    ","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":"","_members_access_role":[],"_members_access_error":"","_links_to":"","_links_to_target":""},"class_list":["post-7026","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/normativeorders.net\/en\/wp-json\/wp\/v2\/pages\/7026"}],"collection":[{"href":"https:\/\/normativeorders.net\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/normativeorders.net\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/normativeorders.net\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/normativeorders.net\/en\/wp-json\/wp\/v2\/comments?post=7026"}],"version-history":[{"count":5,"href":"https:\/\/normativeorders.net\/en\/wp-json\/wp\/v2\/pages\/7026\/revisions"}],"predecessor-version":[{"id":7843,"href":"https:\/\/normativeorders.net\/en\/wp-json\/wp\/v2\/pages\/7026\/revisions\/7843"}],"wp:attachment":[{"href":"https:\/\/normativeorders.net\/en\/wp-json\/wp\/v2\/media?parent=7026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}